{"id":20310,"date":"2025-11-04T12:27:44","date_gmt":"2025-11-04T12:27:44","guid":{"rendered":"https:\/\/radalmedia.lat\/vinas\/?post_type=product&#038;p=20310"},"modified":"2026-05-07T14:20:40","modified_gmt":"2026-05-07T14:20:40","slug":"caja-6-erasmo-blend-library-release-2013","status":"publish","type":"product","link":"https:\/\/caliboro.com\/en\/product\/caja-6-erasmo-blend-library-release-2013\/","title":{"rendered":"Caja 6 Erasmo Blend Library Release 2013"},"content":{"rendered":"<p>Caliboro es un terroir \u00fanico en el coraz\u00f3n del Maule. La uni\u00f3n de<br \/>\neste suelo con la larga tradici\u00f3n de vinos de nuestro fundador, dan<br \/>\nvida a Erasmo. Una tradicional mezcla de Cabernets y Merlot,<br \/>\ncuidado artesanalmente, de gran concentraci\u00f3n y persistencia.<\/p>\n<p>VARIEDAD<br \/>\n57% Cabernet Sauvignon<br \/>\n20% Cabernet Franc<br \/>\n21% Merlot<br \/>\n2% Syrah<\/p>\n<p>CLIMA<br \/>\nMediterr\u00e1neo templado<\/p>\n<p>SUELO<br \/>\nTerrazas del R\u00edo Perquilauqu\u00e9n,<br \/>\nsuelos vivos de origen gran\u00edtico<\/p>\n<p>NOTAS ENOL\u00d3GICAS<br \/>\n\u2022 Cosecha manual seleccionada<br \/>\n\u2022 Fermentaci\u00f3n con levaduras<br \/>\nnativas<br \/>\n\u2022 Sin filtrar<\/p>\n<p>GUARDA<br \/>\n2 inviernos en barricas de roble<br \/>\nfranc\u00e9s de 500 lts. y m\u00ednimo<br \/>\n12 meses en botella<\/p>\n<p>INFORMACI\u00d3N T\u00c9CNICA<br \/>\nAlcohol: 14.5%<br \/>\npH: 3.34<br \/>\nAcidez Total: 6.19 g\/L (tart\u00e1rica)<br \/>\nAz\u00facar residual: 1.19 g\/L<\/p>\n<p>NOTAS DE CATA<\/p>\n<p>MARIDAJE IDEAL<br \/>\nCarnes rojas estofadas<br \/>\nColor: Rojo vivo y profundo<br \/>\nNariz: Frutas rojas frescas, finas<br \/>\nespecies, recuerdos nativos<br \/>\nBoca: Jugoso, equilibrado, de rica<br \/>\nacidez y balanceados taninos que<br \/>\nlo hacen persistente y de largo<br \/>\nretrogusto<br \/>\nEMBOTELLADO<br \/>\nEnero 2013<\/p>\n<p>ORIGEN<br \/>\nCaliboro, Valle del Maule<\/p>\n<p>EDAD VI\u00d1EDOS<br \/>\n22 a\u00f1os<\/p>","protected":false},"excerpt":{"rendered":"<p>Caliboro es un terroir \u00fanico en el coraz\u00f3n del Maule. La uni\u00f3n de<br \/>\neste suelo con la larga tradici\u00f3n de vinos de nuestro fundador, dan<br \/>\nvida a Erasmo. Una tradicional mezcla de Cabernets y Merlot,<br \/>\ncuidado artesanalmente, de gran concentraci\u00f3n y persistencia.<\/p>","protected":false},"featured_media":20308,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[201],"product_tag":[],"class_list":{"0":"post-20310","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-blend","8":"first","9":"instock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caja 6 Erasmo Blend Library Release 2013 - Erasmo<\/title>\n<meta name=\"description\" content=\"Caliboro es un terroir \u00fanico en el coraz\u00f3n del Maule. La uni\u00f3n deeste suelo con la larga tradici\u00f3n de vinos de nuestro fundador, dan vida a Erasmo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/caliboro.com\/en\/product\/caja-6-erasmo-blend-library-release-2013\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caja 6 Erasmo Blend Library Release 2013 - Erasmo\" \/>\n<meta property=\"og:description\" content=\"Caliboro es un terroir \u00fanico en el coraz\u00f3n del Maule. La uni\u00f3n deeste suelo con la larga tradici\u00f3n de vinos de nuestro fundador, dan vida a Erasmo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/caliboro.com\/en\/product\/caja-6-erasmo-blend-library-release-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"Erasmo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T14:20:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/caliboro.com\/wp-content\/uploads\/2025\/11\/6-Library-Release-todos-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/\",\"url\":\"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/\",\"name\":\"Caja 6 Erasmo Blend Library Release 2013 - Erasmo\",\"isPartOf\":{\"@id\":\"https:\/\/caliboro.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/caliboro.com\/wp-content\/uploads\/2025\/11\/6-Library-Release-todos-1.png\",\"datePublished\":\"2025-11-04T12:27:44+00:00\",\"dateModified\":\"2026-05-07T14:20:40+00:00\",\"description\":\"Caliboro es un terroir \u00fanico en el coraz\u00f3n del Maule. La uni\u00f3n deeste suelo con la larga tradici\u00f3n de vinos de nuestro fundador, dan vida a Erasmo.\",\"breadcrumb\":{\"@id\":\"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#primaryimage\",\"url\":\"https:\/\/caliboro.com\/wp-content\/uploads\/2025\/11\/6-Library-Release-todos-1.png\",\"contentUrl\":\"https:\/\/caliboro.com\/wp-content\/uploads\/2025\/11\/6-Library-Release-todos-1.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/caliboro.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/caliboro.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caja 6 Erasmo Blend Library Release 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/caliboro.com\/#website\",\"url\":\"https:\/\/caliboro.com\/\",\"name\":\"Erasmo\",\"description\":\"Erasmo\",\"publisher\":{\"@id\":\"https:\/\/caliboro.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/caliboro.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/caliboro.com\/#organization\",\"name\":\"Erasmo\",\"url\":\"https:\/\/caliboro.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/caliboro.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/caliboro.com\/wp-content\/uploads\/2022\/02\/cropped-LOGO-ERASMO-COLOR.png\",\"contentUrl\":\"https:\/\/caliboro.com\/wp-content\/uploads\/2022\/02\/cropped-LOGO-ERASMO-COLOR.png\",\"width\":2362,\"height\":1792,\"caption\":\"Erasmo\"},\"image\":{\"@id\":\"https:\/\/caliboro.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caja 6 Erasmo Blend Library Release 2013 - Erasmo","description":"Caliboro es un terroir \u00fanico en el coraz\u00f3n del Maule. La uni\u00f3n deeste suelo con la larga tradici\u00f3n de vinos de nuestro fundador, dan vida a Erasmo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/caliboro.com\/en\/product\/caja-6-erasmo-blend-library-release-2013\/","og_locale":"en_US","og_type":"article","og_title":"Caja 6 Erasmo Blend Library Release 2013 - Erasmo","og_description":"Caliboro es un terroir \u00fanico en el coraz\u00f3n del Maule. La uni\u00f3n deeste suelo con la larga tradici\u00f3n de vinos de nuestro fundador, dan vida a Erasmo.","og_url":"https:\/\/caliboro.com\/en\/product\/caja-6-erasmo-blend-library-release-2013\/","og_site_name":"Erasmo","article_modified_time":"2026-05-07T14:20:40+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/caliboro.com\/wp-content\/uploads\/2025\/11\/6-Library-Release-todos-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/","url":"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/","name":"Caja 6 Erasmo Blend Library Release 2013 - Erasmo","isPartOf":{"@id":"https:\/\/caliboro.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#primaryimage"},"image":{"@id":"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/caliboro.com\/wp-content\/uploads\/2025\/11\/6-Library-Release-todos-1.png","datePublished":"2025-11-04T12:27:44+00:00","dateModified":"2026-05-07T14:20:40+00:00","description":"Caliboro es un terroir \u00fanico en el coraz\u00f3n del Maule. La uni\u00f3n deeste suelo con la larga tradici\u00f3n de vinos de nuestro fundador, dan vida a Erasmo.","breadcrumb":{"@id":"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#primaryimage","url":"https:\/\/caliboro.com\/wp-content\/uploads\/2025\/11\/6-Library-Release-todos-1.png","contentUrl":"https:\/\/caliboro.com\/wp-content\/uploads\/2025\/11\/6-Library-Release-todos-1.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/caliboro.com\/product\/caja-6-erasmo-blend-library-release-2013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/caliboro.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/caliboro.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Caja 6 Erasmo Blend Library Release 2013"}]},{"@type":"WebSite","@id":"https:\/\/caliboro.com\/#website","url":"https:\/\/caliboro.com\/","name":"Erasmo","description":"Erasmo","publisher":{"@id":"https:\/\/caliboro.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/caliboro.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/caliboro.com\/#organization","name":"Erasmo","url":"https:\/\/caliboro.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/caliboro.com\/#\/schema\/logo\/image\/","url":"https:\/\/caliboro.com\/wp-content\/uploads\/2022\/02\/cropped-LOGO-ERASMO-COLOR.png","contentUrl":"https:\/\/caliboro.com\/wp-content\/uploads\/2022\/02\/cropped-LOGO-ERASMO-COLOR.png","width":2362,"height":1792,"caption":"Erasmo"},"image":{"@id":"https:\/\/caliboro.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/caliboro.com\/en\/wp-json\/wp\/v2\/product\/20310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caliboro.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/caliboro.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/caliboro.com\/en\/wp-json\/wp\/v2\/comments?post=20310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caliboro.com\/en\/wp-json\/wp\/v2\/media\/20308"}],"wp:attachment":[{"href":"https:\/\/caliboro.com\/en\/wp-json\/wp\/v2\/media?parent=20310"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/caliboro.com\/en\/wp-json\/wp\/v2\/product_brand?post=20310"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/caliboro.com\/en\/wp-json\/wp\/v2\/product_cat?post=20310"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/caliboro.com\/en\/wp-json\/wp\/v2\/product_tag?post=20310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}